{"id":89,"count":7,"description":"News transferred to the archive","link":"https:\/\/www.checkpoint.fi\/en\/category\/news-archive-en\/","name":"News archive","slug":"news-archive-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News archive Archives - Checkpoint<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.checkpoint.fi\/en\/category\/news-archive-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News archive Archives - Checkpoint\" \/>\n<meta property=\"og:description\" content=\"News transferred to the archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.checkpoint.fi\/en\/category\/news-archive-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Checkpoint\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.checkpoint.fi\\\/en\\\/category\\\/news-archive-en\\\/\",\"url\":\"https:\\\/\\\/www.checkpoint.fi\\\/en\\\/category\\\/news-archive-en\\\/\",\"name\":\"News archive Archives - Checkpoint\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.checkpoint.fi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.checkpoint.fi\\\/en\\\/category\\\/news-archive-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.checkpoint.fi\\\/en\\\/category\\\/news-archive-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.checkpoint.fi\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News archive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.checkpoint.fi\\\/#website\",\"url\":\"https:\\\/\\\/www.checkpoint.fi\\\/\",\"name\":\"Checkpoint\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.checkpoint.fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News archive Archives - Checkpoint","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.checkpoint.fi\/en\/category\/news-archive-en\/","og_locale":"en_US","og_type":"article","og_title":"News archive Archives - Checkpoint","og_description":"News transferred to the archive","og_url":"https:\/\/www.checkpoint.fi\/en\/category\/news-archive-en\/","og_site_name":"Checkpoint","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.checkpoint.fi\/en\/category\/news-archive-en\/","url":"https:\/\/www.checkpoint.fi\/en\/category\/news-archive-en\/","name":"News archive Archives - Checkpoint","isPartOf":{"@id":"https:\/\/www.checkpoint.fi\/#website"},"breadcrumb":{"@id":"https:\/\/www.checkpoint.fi\/en\/category\/news-archive-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.checkpoint.fi\/en\/category\/news-archive-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.checkpoint.fi\/en\/home\/"},{"@type":"ListItem","position":2,"name":"News archive"}]},{"@type":"WebSite","@id":"https:\/\/www.checkpoint.fi\/#website","url":"https:\/\/www.checkpoint.fi\/","name":"Checkpoint","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.checkpoint.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.checkpoint.fi\/en\/wp-json\/wp\/v2\/categories\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.checkpoint.fi\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.checkpoint.fi\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.checkpoint.fi\/en\/wp-json\/wp\/v2\/posts?categories=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}